{"id":11107,"date":"2024-04-09T08:59:44","date_gmt":"2024-04-09T06:59:44","guid":{"rendered":"https:\/\/catedra.us.es\/catedrartveus\/politica-de-cookies\/"},"modified":"2024-04-09T08:59:44","modified_gmt":"2024-04-09T06:59:44","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/catedra.us.es\/catedrartveus\/politica-de-cookies\/","title":{"rendered":"Pol\u00edtica de cookies"},"content":{"rendered":"\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Esta pol\u00edtica de cookies fue actualizada por \u00faltima vez el 9 de abril de 2024 y se aplica a los ciudadanos y residentes legales permanentes del Espacio Econ\u00f3mico Europeo y Suiza.<\/i><br><\/p><h2>1. Introducci\u00f3n<\/h2><p>Nuestra web, <a href=\"https:\/\/catedra.us.es\/catedrartveus\">https:\/\/catedra.us.es\/catedrartveus<\/a> (en adelante: \u00abla web\u00bb) utiliza cookies y otras tecnolog\u00edas relacionadas (para mayor comodidad, todas las tecnolog\u00edas se denominan \u00abcookies\u00bb). Las cookies tambi\u00e9n son colocadas por terceros a los que hemos contratado. En el siguiente documento te informamos sobre el uso de cookies en nuestra web.<\/p><h2>2. \u00bfQu\u00e9 son las cookies?<\/h2><p>Una cookie es un peque\u00f1o archivo que se env\u00eda junto con las p\u00e1ginas de esta web y que tu navegador almacena en el disco duro de su ordenador u otro dispositivo. La informaci\u00f3n almacenada puede ser devuelta a nuestros servidores o a los servidores de terceros apropiados durante una visita posterior.<\/p><h2>3. \u00bfQu\u00e9 son los scripts?<\/h2><p>Un script es un fragmento de c\u00f3digo de programa que se utiliza para hacer que nuestra web funcione correctamente y de forma interactiva. Este c\u00f3digo se ejecuta en nuestro servidor o en tu dispositivo.<\/p><h2>4. \u00bfQu\u00e9 es una baliza web?<\/h2><p>Una baliza web (o una etiqueta de p\u00edxel) es una peque\u00f1a e invisible pieza de texto o imagen en una web que se utiliza para monitorear el tr\u00e1fico en una web. Para ello, se almacenan varios datos sobre usted mediante estas balizas web.<\/p><h2>5. Cookies<\/h2><h3>5.1 Cookies t\u00e9cnicas o funcionales<\/h3><p>Algunas cookies aseguran que ciertas partes de la web funcionen correctamente y que tus preferencias de usuario sigan record\u00e1ndose. Al colocar cookies funcionales, te facilitamos la visita a nuestra web. De esta manera, no necesitas introducir repetidamente la misma informaci\u00f3n cuando visitas nuestra web y, por ejemplo, los art\u00edculos permanecen en tu cesta de la compra hasta que hayas pagado. Podemos colocar estas cookies sin tu consentimiento.<\/p><h3>5.2 Cookies de marketing\/seguimiento<\/h3><p>Las cookies de marketing\/seguimiento son cookies, o cualquier otra forma de almacenamiento local, usadas para crear perfiles de usuario para mostrar publicidad o para hacer el seguimiento del usuario en esta web o en varias webs con fines de marketing similares.<\/p><h3>5.3 Redes sociales<\/h3><p>En nuestra web hemos incluido contenido de Facebook, X (Formerly Twitter), Instagram y LinkedIn para promover p\u00e1ginas web (p.ej.: \u00abMe gusta\u00bb, \u00abPinear\u00bb) o compartir (p.ej.: \u00abtuitear\u00bb) en redes sociales como Facebook, X (Formerly Twitter), Instagram y LinkedIn. Este contenido est\u00e1 incrustado con c\u00f3digo derivado de Facebook, X (Formerly Twitter), Instagram y LinkedIn y guarda cookies. Este contenido podr\u00eda procesar cierta informaci\u00f3n para anuncios personalizados.<\/p><p>Por favor lea la pol\u00edtica de privacidad de estas redes sociales (que puede cambiar frecuentemente) para saber que hacen con sus datos (personales) que procesan usando estas cookies. Los datos que reciben son anonimizados lo m\u00e1ximo posible. Facebook, X (Formerly Twitter), Instagram y LinkedIn est\u00e1n ubicados en los Estados Unidos.<\/p><h2>6. Cookies usadas<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WooCommerce<\/h3>\n\t\t<p>Estad\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_woocommerce\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service woocommerce<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_woocommerce\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"woocommerce\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos WooCommerce para gesti\u00f3n de la tienda web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/woocommerce\/\">Leer m\u00e1s acerca de WooCommerce<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Estos datos no se comparten con terceros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/woocommerce\/history-store\/\">History.store<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacenar la \u00faltima visita<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Funcional<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos WordPress para desarrollo de sitios web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordpress\/\">Leer m\u00e1s acerca de WordPress<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Estos datos no se comparten con terceros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wpemojisettingssupports\/\">wpEmojiSettingsSupports<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">sesi\u00f3n<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar detalles del navegador<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_test_cookie\/\">wordpress_test_cookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">sesi\u00f3n<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Chequear si se pueden instalar cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings-time\/\">wp-settings-time-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar las preferencias de los usuarios<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings\/\">wp-settings-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar las preferencias de los usuarios<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_logged_in_\/\">wordpress_logged_in_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Mantener los usuarios logeados<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Analytics<\/h3>\n\t\t<p>Estad\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_google-analytics\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-analytics<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-analytics\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-analytics\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Google Analytics para estad\u00edsticas del sitio web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-analytics\/\">Leer m\u00e1s acerca de Google Analytics<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">pol\u00edtica de privacidad de Google Analytics<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_ga\/\">_ga<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">2 a\u00f1os<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Contar y rastrear p\u00e1ginas vistas<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_gid\/\">_gid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 d\u00eda<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Contar y rastrear p\u00e1ginas vistas<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_ga_\/\">_ga_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Contar y rastrear p\u00e1ginas vistas<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_gat_gtag_ua_-2\/\">_gat_gtag_UA_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 minuto<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacenar un ID de usuario \u00fanico<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Wordfence<\/h3>\n\t\t<p>Funcional<\/p>\n\t\t<label for=\"cmplz_service_wordfence\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordfence<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordfence\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordfence\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Wordfence para seguridad del sitio web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordfence\/\">Leer m\u00e1s acerca de Wordfence<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.wordfence.com\/privacy-policy\/\">pol\u00edtica de privacidad de Wordfence<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordfence\/wfwaf-authcookie\/\">wfwaf-authcookie*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 d\u00eda<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Determina si el usuario ha iniciado sesi\u00f3n<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Fonts<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-fonts\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Google Fonts para mostrar fuentes web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-fonts\/\">Leer m\u00e1s acerca de Google Fonts<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">pol\u00edtica de privacidad de Google Fonts<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-fonts\/tcb_google_fonts\/\">Google Fonts API<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">nada<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Solicitar la direcci\u00f3n IP del usuario<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Maps<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_google-maps\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-maps<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-maps\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-maps\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Google Maps para mostrar mapas. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-maps\/\">Leer m\u00e1s acerca de Google Maps<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">pol\u00edtica de privacidad de Google Maps<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-maps\/google-maps-api\/\">Google Maps API<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">nada<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Solicitar la direcci\u00f3n IP del usuario<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>YouTube<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_youtube\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service youtube<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_youtube\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"youtube\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos YouTube para mostrar video. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/youtube\/\">Leer m\u00e1s acerca de YouTube<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">pol\u00edtica de privacidad de YouTube<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/gps\/\">GPS<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">sesi\u00f3n<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar datos de ubicaci\u00f3n<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/visitor_info1_live\/\">VISITOR_INFO1_LIVE<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">6 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Habilitar la publicaci\u00f3n de anuncios o retargeting<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/ysc\/\">YSC<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">sesi\u00f3n<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Store and track interaction<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/pref\/\">PREF<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">8 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar las preferencias de los usuarios<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Facebook<\/h3>\n\t\t<p>Marketing, Funcional<\/p>\n\t\t<label for=\"cmplz_service_facebook\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service facebook<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_facebook\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"facebook\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Facebook para mostrar publicaciones sociales recientes y\/o botones sociales para compartir en redes sociales. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/facebook\/\">Leer m\u00e1s acerca de Facebook<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.facebook.com\/policy\/cookies\">pol\u00edtica de privacidad de Facebook<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbc\/\">_fbc<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">2 a\u00f1os<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacenar la \u00faltima visita<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/fbm_\/\">fbm*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar detalles de la cuenta<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/xs\/\">xs<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">3 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacena una ID de sesi\u00f3n \u00fanica<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/fr\/\">fr<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">3 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Habilitar la publicaci\u00f3n de anuncios o retargeting<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/act\/\">act<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">90 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Mantener los usuarios logeados<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbp\/\">_fbp<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">3 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacenar y realizar un seguimiento de las visitas a trav\u00e9s de m\u00faltiples sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/datr\/\">datr<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">2 a\u00f1os<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Proporcionar prevenci\u00f3n de fraude<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/c_user\/\">c_user<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">30 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacenar un ID de usuario \u00fanico<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/sb\/\">sb<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">2 a\u00f1os<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar detalles del navegador<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbm_\/\">*_fbm_<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar detalles de la cuenta<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/wd\/\">wd<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 semana<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Determinar la resoluci\u00f3n de pantalla<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/csm\/\">csm<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">90 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Proporcionar prevenci\u00f3n de fraude<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/actppresence\/\">actppresence<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">sesi\u00f3n<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacenar y rastrear si la pesta\u00f1a del navegador est\u00e1 activa<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Twitter<\/h3>\n\t\t<p>Funcional, Marketing<\/p>\n\t\t<label for=\"cmplz_service_twitter\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service twitter<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_twitter\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"twitter\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Twitter para mostrar publicaciones sociales recientes y\/o botones sociales para compartir en redes sociales. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/twitter\/\">Leer m\u00e1s acerca de Twitter<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/twitter.com\/en\/privacy\">pol\u00edtica de privacidad de Twitter<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/twitter\/local_storage_support_test\/\">local_storage_support_test<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Cargar la funcionalidad de equilibrio de carga<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/twitter\/metrics_token\/\">metrics_token<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacenar si el usuario ha visto contenido incrustado<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>LinkedIn<\/h3>\n\t\t<p>Funcional, Marketing, Estad\u00edsticas, Preferencias<\/p>\n\t\t<label for=\"cmplz_service_linkedin\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service linkedin<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_linkedin\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"linkedin\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos LinkedIn para mostrar publicaciones sociales recientes y\/o botones sociales para compartir en redes sociales. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/linkedin\/\">Leer m\u00e1s acerca de LinkedIn<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\">pol\u00edtica de privacidad de LinkedIn<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/auto-draft-20\/\">sdsc<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">sesi\u00f3n<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Cargar la funcionalidad de equilibrio de carga<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/auto-draft-16\/\">li_gc<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">6 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar preferencias de consentimiento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/bizographicsoptout\/\">BizographicsOptOut<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">10 a\u00f1os<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar preferencias de privacidad<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/auto-draft-19\/\">lms_ads<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">30 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacenar y realizar un seguimiento de las visitas a trav\u00e9s de m\u00faltiples sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/_guid\/\">_guid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">90 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacenar y rastrear la identidad de un visitante<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/li-oatml\/\">li-oatml<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 mes<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Habilitar la publicaci\u00f3n de anuncios o retargeting<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/li_sugr\/\">li_sugr<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">90 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacenar y rastrear la identidad de un visitante<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/usermatchhistory\/\">UserMatchHistory<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">30 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Habilitar la publicaci\u00f3n de anuncios o retargeting<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/auto-draft-18\/\">lms_analytics<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">30 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacenar y rastrear la identidad de un visitante<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/analyticssynchistory\/\">AnalyticsSyncHistory<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">30 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacenar y realizar un seguimiento de las visitas a trav\u00e9s de m\u00faltiples sitios web<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Preferencias<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/li_alerts\/\">li_alerts<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar si un mensaje ha sido mostrado<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/bcookie-2\/\">bcookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar detalles del navegador<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/lidc\/\">lidc<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 d\u00eda<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Cargar la funcionalidad de equilibrio de carga<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/linkedin\/bscookie\/\">bscookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Mantener los usuarios logeados<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Complianz<\/h3>\n\t\t<p>Funcional<\/p>\n\t\t<label for=\"cmplz_service_complianz\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service complianz<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_complianz\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"complianz\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Complianz para gesti\u00f3n del consentimiento de cookies. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/complianz\/\">Leer m\u00e1s acerca de Complianz<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Estos datos no se comparten con terceros.&nbsp;Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/complianz.io\/legal\/privacy-statement\/\">pol\u00edtica de privacidad de Complianz<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_consented_services\/\">cmplz_consented_services<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar preferencias de consentimiento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_policy_id\/\">cmplz_policy_id<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacenar la ID de la pol\u00edtica de cookies aceptada<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_marketing\/\">cmplz_marketing<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar preferencias de consentimiento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_statistics\/\">cmplz_statistics<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar preferencias de consentimiento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_preferences\/\">cmplz_preferences<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar preferencias de consentimiento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_functional\/\">cmplz_functional<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar preferencias de consentimiento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_banner-status\/\">cmplz_banner-status<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Store if the cookie banner has been dismissed<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Varios<\/h3>\n\t\t<p>Prop\u00f3sito pendiente de investigaci\u00f3n<\/p>\n\t\t<label for=\"cmplz_service_varios\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service varios<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_varios\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"varios\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>El intercambio de datos est\u00e1 pendiente de investigaci\u00f3n<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Prop\u00f3sito pendiente de investigaci\u00f3n<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">copiedShortcode<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/basel_cookies_\/\">basel_cookies_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">CKUS<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consentimiento<\/h2><p>Cuando visites nuestra web por primera vez, te mostraremos una ventana emergente con una explicaci\u00f3n sobre las cookies. Tan pronto como hagas clic en \u00abGuardar preferencias\u00bb, aceptas que usemos las categor\u00edas de cookies y plugins que has seleccionado en la ventana emergente, tal y como se describe en esta pol\u00edtica de cookies. Puedes desactivar el uso de cookies a trav\u00e9s de tu navegador, pero, por favor, ten en cuenta que nuestra web puede dejar de funcionar correctamente.<\/p><h3>7.1 Gestiona tus ajustes de consentimiento<\/h3><div id=\"cmplz-manage-consent-container-nojavascript\">Has cargado la pol\u00edtica de cookies sin compatibilidad con JavaScript.&nbsp;En AMP, puedes utilizar el bot\u00f3n de gestionar el consentimiento en la parte inferior de la p\u00e1gina.<\/div><div id=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Activaci\u00f3n\/desactivaci\u00f3n y borrado de cookies<\/h2><p>Puedes utilizar tu navegador de Internet para eliminar las cookies de forma autom\u00e1tica o manual. Tambi\u00e9n puedes especificar que ciertas cookies no pueden ser colocadas. Otra opci\u00f3n es cambiar los ajustes de tu navegador de Internet para que recibas un mensaje cada vez que se coloca una cookie. Para obtener m\u00e1s informaci\u00f3n sobre estas opciones, consulta las instrucciones de la secci\u00f3n \u00abAyuda\u00bb de tu navegador.<\/p><p>Ten en cuenta que nuestra web puede no funcionar correctamente si todas las cookies est\u00e1n desactivadas. Si borras las cookies de tu navegador, se volver\u00e1n a colocar despu\u00e9s de tu consentimiento cuando vuelvas a visitar nuestras webs.<\/p><h2>9. Tus derechos con respecto a los datos personales<\/h2><p>Tienes los siguientes derechos con respecto a tus datos personales:<\/p><ul>\n                    <li>Tiene derecho a saber por qu\u00e9 se necesitan tus datos personales, qu\u00e9 suceder\u00e1 con ellos y durante cu\u00e1nto tiempo se conservar\u00e1n.<\/li>\n                    <li>Derecho de acceso: tienes derecho a acceder a tus datos personales que conocemos.<\/li>\n                    <li>Derecho de rectificaci\u00f3n: tienes derecho a completar, rectificar, borrar o bloquear tus datos personales cuando lo desees.<\/li>\n                    <li>Si nos das tu consentimiento para procesar tus datos, tienes derecho a revocar dicho consentimiento y a que se eliminen tus datos personales.<\/li>\n                    <li>Derecho de cesi\u00f3n de tus datos: tienes derecho a solicitar todos tus datos personales al responsable del tratamiento y a transferirlos \u00edntegramente a otro responsable del tratamiento.<\/li>\n                    <li>Derecho de oposici\u00f3n: puedes oponerte al tratamiento de tus datos. Nosotros cumplimos con esto, a menos que existan motivos justificados para el procesamiento.<\/li>\n                <\/ul><p>Para ejercer estos derechos, por favor, contacta con nosotros. Por favor, consulta los detalles de contacto en la parte inferior de esta pol\u00edtica de cookies. Si tienes alguna queja sobre c\u00f3mo gestionamos tus datos, nos gustar\u00eda que nos la hicieras saber, pero tambi\u00e9n tienes derecho a enviar una queja a la autoridad supervisora (la autoridad de protecci\u00f3n de datos).<\/p><h2>10. Datos de contacto<\/h2><p>Para preguntas y\/o comentarios sobre nuestra pol\u00edtica de cookies y esta declaraci\u00f3n, por favor, contacta con nosotros usando los siguientes datos de contacto:<\/p><p><span class=\"cmplz-contact-organisation\">UNIVERSIDAD DE SEVILLA<\/span><br>\n                      <span class=\"cmplz-contact-address\">C\/ S. Fernando, 4 (C.P. 41004) SEVILLA<\/span><br>\n                      <span class=\"cmplz-contact-country\">Espa\u00f1a<\/span><br>\n                      <span class=\"cmplz-contact-domain\">Web: <a href=\"https:\/\/catedra.us.es\/catedrartveus\">https:\/\/catedra.us.es\/catedrartveus<\/a><\/span><br>\n                      <span class=\"cmplz-contact-email\">Correo electr\u00f3nico: <span class=\"cmplz-obfuscate\">&#099;&#097;te&#100;r&#097;rtveu&#115;@<span class=\"cmplz-fmail-domain\">&#101;x.c&#111;m<\/span>u&#115;&#046;&#101;&#115;<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\"><\/span><\/p><p>Esta pol\u00edtica de cookies se ha sincronizado con <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">cookiedatabase.org<\/a> el 15 de junio de 2026.<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"Esta pol\u00edtica de cookies fue actualizada por \u00faltima vez el 9 de abril de 2024 y se aplica a los","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-11107","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de cookies - C\u00e1tedra RTVE Universidad de Sevilla<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/catedra.us.es\/catedrartveus\/politica-de-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de cookies - C\u00e1tedra RTVE Universidad de Sevilla\" \/>\n<meta property=\"og:url\" content=\"https:\/\/catedra.us.es\/catedrartveus\/politica-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"C\u00e1tedra RTVE Universidad de Sevilla\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/catedra.us.es\\\/catedrartveus\\\/politica-de-cookies\\\/\",\"url\":\"https:\\\/\\\/catedra.us.es\\\/catedrartveus\\\/politica-de-cookies\\\/\",\"name\":\"Pol\u00edtica de cookies - C\u00e1tedra RTVE Universidad de Sevilla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/catedra.us.es\\\/catedrartveus\\\/#website\"},\"datePublished\":\"2024-04-09T06:59:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/catedra.us.es\\\/catedrartveus\\\/politica-de-cookies\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/catedra.us.es\\\/catedrartveus\\\/politica-de-cookies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/catedra.us.es\\\/catedrartveus\\\/politica-de-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/catedra.us.es\\\/catedrartveus\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/catedra.us.es\\\/catedrartveus\\\/#website\",\"url\":\"https:\\\/\\\/catedra.us.es\\\/catedrartveus\\\/\",\"name\":\"C\u00e1tedra RTVE Universidad de Sevilla\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/catedra.us.es\\\/catedrartveus\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de cookies - C\u00e1tedra RTVE Universidad de Sevilla","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/catedra.us.es\/catedrartveus\/politica-de-cookies\/","og_locale":"es_ES","og_type":"article","og_title":"Pol\u00edtica de cookies - C\u00e1tedra RTVE Universidad de Sevilla","og_url":"https:\/\/catedra.us.es\/catedrartveus\/politica-de-cookies\/","og_site_name":"C\u00e1tedra RTVE Universidad de Sevilla","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/catedra.us.es\/catedrartveus\/politica-de-cookies\/","url":"https:\/\/catedra.us.es\/catedrartveus\/politica-de-cookies\/","name":"Pol\u00edtica de cookies - C\u00e1tedra RTVE Universidad de Sevilla","isPartOf":{"@id":"https:\/\/catedra.us.es\/catedrartveus\/#website"},"datePublished":"2024-04-09T06:59:44+00:00","breadcrumb":{"@id":"https:\/\/catedra.us.es\/catedrartveus\/politica-de-cookies\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/catedra.us.es\/catedrartveus\/politica-de-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/catedra.us.es\/catedrartveus\/politica-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/catedra.us.es\/catedrartveus\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de cookies"}]},{"@type":"WebSite","@id":"https:\/\/catedra.us.es\/catedrartveus\/#website","url":"https:\/\/catedra.us.es\/catedrartveus\/","name":"C\u00e1tedra RTVE Universidad de Sevilla","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/catedra.us.es\/catedrartveus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/catedra.us.es\/catedrartveus\/wp-json\/wp\/v2\/pages\/11107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catedra.us.es\/catedrartveus\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/catedra.us.es\/catedrartveus\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/catedra.us.es\/catedrartveus\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catedra.us.es\/catedrartveus\/wp-json\/wp\/v2\/comments?post=11107"}],"version-history":[{"count":0,"href":"https:\/\/catedra.us.es\/catedrartveus\/wp-json\/wp\/v2\/pages\/11107\/revisions"}],"wp:attachment":[{"href":"https:\/\/catedra.us.es\/catedrartveus\/wp-json\/wp\/v2\/media?parent=11107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}